{"id":6324,"date":"2021-08-05T10:45:27","date_gmt":"2021-08-05T17:45:27","guid":{"rendered":"https:\/\/www.cloroxpro.ca\/?post_type=blog&#038;p=6324"},"modified":"2021-11-22T08:31:47","modified_gmt":"2021-11-22T16:31:47","slug":"conseils-pour-reussir-la-mise-en-service-dun-systeme-de-desinfection-par-pulverisation-electrostatique","status":"publish","type":"blog","link":"https:\/\/www.cloroxpro.ca\/fr\/blog\/conseils-pour-reussir-la-mise-en-service-dun-systeme-de-desinfection-par-pulverisation-electrostatique\/","title":{"rendered":"Conseils pour r\u00e9ussir la mise en service d\u2019un syst\u00e8me de d\u00e9sinfection par pulv\u00e9risation \u00e9lectrostatique"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Avantages de la technologie \u00e9lectrostatique dans les \u00e9tablissements de soins de sant\u00e9<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La pulv\u00e9risation \u00e9lectrostatique constitue un moyen r\u00e9volutionnaire de d\u00e9sinfecter les surfaces environnantes<sup>1,2<\/sup>. En raison surtout de la pand\u00e9mie de COVID-19, cette technologie gagne rapidement en popularit\u00e9, mais malgr\u00e9 toute l\u2019information disponible \u00e0 ce sujet, la pulv\u00e9risation \u00e9lectrostatique peut pr\u00e9senter certains d\u00e9fis aux \u00e9tablissements qui souhaiteraient l\u2019int\u00e9grer \u00e0 leur protocole de d\u00e9sinfection. Heureusement, nous sommes l\u00e0 pour vous aider. Voici quelques conseils qui vous aideront \u00e0 assurer le succ\u00e8s de la mise en service d\u2019un syst\u00e8me de pulv\u00e9risation \u00e9lectrostatique (SP\u00c9) au sein de votre \u00e9tablissement de soins de sant\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>L\u2019\u00e9ducation est la cl\u00e9 de la r\u00e9ussite.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les SP\u00c9 se pr\u00e9sentent sous diff\u00e9rentes formes, incluant des chariots \u00e0 roulettes, des syst\u00e8mes portatifs du genre \u00absac \u00e0 dos\u00bb et des pulv\u00e9risateurs \u00e0 main, avec ou sans fil<sup>3,4<\/sup>. Le type d\u2019environnement que vos travailleurs sont appel\u00e9s \u00e0 d\u00e9sinfecter peut aider \u00e0 orienter le choix de SP\u00c9, ou encore, \u00e0 d\u00e9terminer si votre \u00e9tablissement requiert l\u2019emploi de plus d\u2019un mod\u00e8le. Par exemple, si votre \u00e9tablissement comporte de grandes aires ouvertes et que le facteur ergonomique doit \u00eatre pris en compte, le choix d\u2019un SP\u00c9 sur roulettes pourrait \u00eatre de mise. En revanche, si vous devez d\u00e9sinfecter des aires encombr\u00e9es, un syst\u00e8me portatif pourrait s\u2019av\u00e9rer plus utile en raison de sa mobilit\u00e9. Pour les endroits plus petits, un syst\u00e8me sans fil, comme un pulv\u00e9risateur \u00e0 main, vous offrirait la commodit\u00e9 et la mobilit\u00e9 n\u00e9cessaires pour couvrir toutes les surfaces. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois que votre \u00e9tablissement a fait son (ou ses) choix, vous pouvez \u00e9galement avoir acc\u00e8s \u00e0 des modules de formation en ligne ou \u00e0 du mat\u00e9riel \u00e9ducatif pour aider \u00e0 former vos travailleurs sur l\u2019emploi du SP\u00c9. De nombreux fabricants de SP\u00c9 ou de produits d\u00e9sinfectants con\u00e7us pour les SP\u00c9 offrent ce type de ressources. N\u2019h\u00e9sitez pas \u00e0 y jeter un coup d\u2019\u0153il!<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1732\" height=\"1154\" src=\"https:\/\/www.cloroxpro.ca\/wp-content\/uploads\/2021\/08\/NI-50052_PPD_DVC_T360_Healthcare-SporeDefense_PatientRoom_Shot_14_.jpg\" alt=\"\" class=\"wp-image-6299\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Assurez-vous d\u2019utiliser un produit d\u00e9sinfectant approuv\u00e9 par Sant\u00e9 Canada pour les pulv\u00e9risateurs \u00e9lectrostatiques<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019il est question de choisir un produit d\u00e9sinfectant pour votre pulv\u00e9risateur \u00e9lectrostatique, il est important de choisir une solution approuv\u00e9e par Sant\u00e9 Canada pour ce type d\u2019appareil<sup>5,6<\/sup>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les renseignements les plus r\u00e9cents de Sant\u00e9 Canada indiquent que les produits d\u00e9sinfectants appliqu\u00e9s au moyen d\u2019un pulv\u00e9risateur \u00e9lectrostatique doivent \u00eatre approuv\u00e9s par le minist\u00e8re, c\u2019est-\u00e0-dire qu\u2019ils doivent porter un DIN. Pour que le produit soit conforme, le mode d\u2019emploi sur l\u2019\u00e9tiquette ma\u00eetresse doit \u00e9galement indiquer \u00abPour pulv\u00e9risateur [ou vaporisateur] \u00e9lectrostatique\u00bb en tant que m\u00e9thode de d\u00e9sinfection<sup>5,6<\/sup>. De plus, si un produit figure dans la liste des d\u00e9sinfectants approuv\u00e9s par Sant\u00e9 Canada et reconnus comme \u00e9tant efficaces contre le virus de la COVID-19, assurez-vous qu\u2019il est clairement identifi\u00e9 comme \u00e9tant destin\u00e9 \u00e0 la pulv\u00e9risation \u00e9lectrostatique<sup>6<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Choisissez des produits qui conviennent aux diff\u00e9rents endroits au sein de votre \u00e9tablissement<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00c9laboration d\u2019un protocole pour les SP\u00c9<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un protocole clair et facile \u00e0 comprendre peut assurer une bonne int\u00e9gration des SP\u00c9 au protocole des \u00e9tablissements de soins de sant\u00e9. Au moment d\u2019\u00e9laborer votre propre protocole, prenez en compte les facteurs suivants:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Assurez-vous que vous poss\u00e9dez tout l\u2019\u00e9quipement de protection personnelle (\u00c9PP) n\u00e9cessaire pour les utilisateurs de votre SP\u00c9. V\u00e9rifiez les exigences en mati\u00e8re d\u2019\u00c9PP en consultant l\u2019\u00e9tiquette du produit, ou encore sa fiche signal\u00e9tique ou son \u00e9tiquette du SIMDUT<sup>1<\/sup>.<\/li><li>Il est d\u00e9conseill\u00e9 d\u2019utiliser un SP\u00c9 dans les endroits occup\u00e9s par des personnes. Pour assurer la s\u00e9curit\u00e9 de tous, v\u00e9rifiez la dur\u00e9e de contact requise par le produit et le d\u00e9lai d\u2019attente avant d\u2019autoriser les gens \u00e0 r\u00e9int\u00e9grer les lieux<sup>1<\/sup>.<\/li><li>Il faut toujours enlever la salet\u00e9 visible avant de d\u00e9sinfecter une surface au moyen d\u2019un SP\u00c9. En l\u2019absence de salet\u00e9 visible, le SP\u00c9 peut \u00eatre utilis\u00e9 pour d\u00e9sinfecter en une seule \u00e9tape.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pour de meilleurs r\u00e9sultats, utilisez votre SP\u00c9 selon une strat\u00e9gie bien d\u00e9finie.<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Le pulv\u00e9risateur \u00e9lectrostatique projette des particules charg\u00e9es qui sont attir\u00e9es par les surfaces et les objets, mais pour obtenir de meilleurs r\u00e9sultats, il est pr\u00e9f\u00e9rable d\u2019orienter le jet directement vers les surfaces cibles, et non rien que dans l\u2019air<sup>1<\/sup>.<\/li><li>V\u00e9rifiez le mode d\u2019emploi de votre SP\u00c9 afin de d\u00e9terminer la distance optimale \u00e0 observer entre les surfaces \u00e0 traiter et la buse du pulv\u00e9risateur (cette distance varie en fonction du type de SP\u00c9 utilis\u00e9). Les surfaces doivent demeurer visiblement mouill\u00e9es pendant toute la dur\u00e9e de contact indiqu\u00e9e sur l\u2019\u00e9tiquette du produit d\u00e9sinfectant<sup>3<\/sup>.<\/li><li>Traitez toujours les surfaces en suivant le m\u00eame trac\u00e9 afin de ne jamais manquer d\u2019endroits.<ul><li>Afin d\u2019assurer une couverture compl\u00e8te, appliquez le produit en effectuant de lents mouvements de va-et-vient et en proc\u00e9dant de haut en bas<sup>3<\/sup>.<\/li><\/ul><ul><li>Commencez au fond de la pi\u00e8ce \u00e0 traiter, puis progressez peu \u00e0 peu vers la porte.<\/li><\/ul><\/li><li>Avant de commencer, v\u00e9rifiez toujours que le produit est compatible avec les surfaces \u00e0 traiter<sup>1<\/sup>. Une fois la dur\u00e9e de contact \u00e9coul\u00e9e, vous devrez peut-\u00eatre essuyer certaines surfaces, telles que les vitres ou les \u00e9crans d\u2019ordinateur, pour \u00e9liminer toute trace de r\u00e9sidu visible.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ces conseils peuvent vous aider \u00e0 int\u00e9grer votre SP\u00c9 avec succ\u00e8s!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>CloroxPro<sup>\u00ae<\/sup> offre plusieurs options de formules d\u00e9sinfectantes approuv\u00e9es pour les SP\u00c9<sup>3<\/sup>.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ingr\u00e9dient actif du nettoyant d\u00e9sinfectant Clorox Total 360<sup>\u00ae<\/sup> (DIN: 02460769) est un compos\u00e9 d\u2019ammonium quaternaire, et la formule ne contient pas d\u2019eau de Javel. Ce produit tue le SRAS-CoV-2 (le virus qui cause la COVID-19) apr\u00e8s 2 minutes de contact et a d\u00e9montr\u00e9 son efficacit\u00e9 contre 54 autres micro-organismes, y compris les virus de la grippe et du rhume (rhinovirus), le SARM et le norovirus. Le nettoyant d\u00e9sinfectant Clorox Total 360<sup>\u00ae<\/sup> peut \u00eatre utilis\u00e9 d\u2019un bout \u00e0 l\u2019autre de votre \u00e9tablissement (incluant les corridors, les halls d\u2019entr\u00e9e, les cuisines et la buanderie) ainsi que dans les ambulances.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9sinfectant nettoyant Spore Defense<sup>MC<\/sup>\u00a0de Clorox Healthcare<sup>\u00ae<\/sup> (DIN: 02494663) contient une faible concentration d\u2019eau de Javel (0,25\u00a0% p\/p d\u2019hypochlorite de sodium). Cette formule est efficace pour d\u00e9truire les virus de la grippe, le norovirus, l\u2019ERV, le SARM et le SRAS-CoV-2 apr\u00e8s 1 minute de contact, et les spores de <em>C. difficile<\/em> apr\u00e8s 5 minutes de contact. Non corrosive et non abrasive, elle est compatible avec un grand nombre de surfaces dures en milieu hospitalier et peut m\u00eame \u00eatre utilis\u00e9e sans danger dans des endroits servant \u00e0 la prestation des soins aux b\u00e9n\u00e9ficiaires, tels que les aires d\u2019isolement, les salles d\u2019urgence et les chambres de patients, ou encore, pour d\u00e9sinfecter les toilettes publiques, le mat\u00e9riel de transport des patients et les v\u00e9hicules d\u2019urgence. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, l\u2019assainissant et d\u00e9sinfectant \u00e0 usage quotidien Clorox<sup>\u00ae<\/sup> Anywhere<sup>\u00ae<\/sup> (DIN: 02495716) contient de l\u2019acide hypochloreux \u00e0 raison de 0,014\u00a0% p\/p, une formulation id\u00e9ale pour les surfaces qui entrent en contact avec les aliments. Ce produit \u00e9limine 99,9\u00a0% des bact\u00e9ries et des virus que l\u2019on retrouve commun\u00e9ment sur les surfaces de contact alimentaire, tels que les salmonelles et <em>E. coli<\/em>, ainsi que les virus du rhume et de la grippe. L\u2019assainissant et d\u00e9sinfectant \u00e0 usage quotidien Clorox<sup>\u00ae<\/sup> Anywhere<sup>\u00ae<\/sup> peut \u00eatre utilis\u00e9 n\u2019importe o\u00f9, aussi bien dans les aires de pr\u00e9paration des aliments et les caf\u00e9t\u00e9rias que sur les interrupteurs muraux et les poign\u00e9es de porte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.cloroxpro.ca\/fr\/produits\/clorox-fr\/systeme-total-360\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour en savoir plus sur les produits con\u00e7us pour les pulv\u00e9risateurs \u00e9lectrostatiques Clorox Total 360<sup>\u00ae<\/sup>, visitez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9f\u00e9rences<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Velez K. Electrostatic technology: A new method for surface disinfection. CloroxPro Canada, 7 d\u00e9cembre 2020.<\/li><li>Velez K. Evaluating Electrostatic Sprayers for Surface Disinfection. CloroxPro Canada. 2020.<\/li><li>CloroxPro Canada, syst\u00e8me CloroxTotal 360<sup>\u00ae<\/sup>. <a href=\"https:\/\/www.cloroxpro.ca\/fr\/produits\/clorox-fr\/systeme-total-360\/\">https:\/\/www.cloroxpro.ca\/fr\/produits\/clorox-fr\/systeme-total-360\/<\/a>. Consult\u00e9 le 7 juillet 2021.<\/li><li>CloroxPro Canada. Clorox TurboPro\u2122 Handheld Electrostatic Sprayer. <a href=\"https:\/\/www.cloroxpro.ca\/products\/clorox\/turbopro\/\">https:\/\/www.cloroxpro.ca\/products\/clorox\/turbopro\/<\/a>. Consult\u00e9 le 7 juillet 2021.<\/li><li>CloroxPro Canada. Donn\u00e9es fich\u00e9es. 18 d\u00e9cembre 2020. [R\u00e9ponse de Sant\u00e9 Canada \u00e0 S. Coombs].<\/li><li>Gouvernement du Canada. D\u00e9sinfectants pour surfaces dures et d\u00e9sinfectants pour les mains (COVID-19) : Liste de d\u00e9sinfectants dont l\u2019utilisation contre la COVID-19 a \u00e9t\u00e9 prouv\u00e9e. https:\/\/www.canada.ca\/fr\/sante-canada\/services\/medicaments-produits-sante\/desinfectants\/covid-19\/liste.html. Consult\u00e9 le 22 avril 2021.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a9 2021 The Clorox Company<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avantages de la technologie \u00e9lectrostatique dans les \u00e9tablissements de soins de sant\u00e9 La pulv\u00e9risation \u00e9lectrostatique constitue un moyen r\u00e9volutionnaire de d\u00e9sinfecter les surfaces environnantes1,2. En raison surtout de la pand\u00e9mie de COVID-19, cette technologie gagne rapidement en popularit\u00e9, mais malgr\u00e9 toute l\u2019information disponible \u00e0 ce sujet, la pulv\u00e9risation \u00e9lectrostatique peut pr\u00e9senter certains d\u00e9fis aux \u00e9tablissements [&hellip;]<\/p>\n","protected":false},"featured_media":6299,"template":"","cp_term_topic":[169],"cp_term_author":[],"class_list":["post-6324","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cloroxpro.ca\/fr\/wp-json\/wp\/v2\/blog\/6324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cloroxpro.ca\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.cloroxpro.ca\/fr\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/www.cloroxpro.ca\/fr\/wp-json\/wp\/v2\/blog\/6324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cloroxpro.ca\/fr\/wp-json\/wp\/v2\/media\/6299"}],"wp:attachment":[{"href":"https:\/\/www.cloroxpro.ca\/fr\/wp-json\/wp\/v2\/media?parent=6324"}],"wp:term":[{"taxonomy":"cp_term_topic","embeddable":true,"href":"https:\/\/www.cloroxpro.ca\/fr\/wp-json\/wp\/v2\/cp_term_topic?post=6324"},{"taxonomy":"cp_term_author","embeddable":true,"href":"https:\/\/www.cloroxpro.ca\/fr\/wp-json\/wp\/v2\/cp_term_author?post=6324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}